{"id":18300,"date":"2023-10-19T14:40:30","date_gmt":"2023-10-19T14:40:30","guid":{"rendered":"https:\/\/www.verdecchia.it\/catalogo\/uncategorized\/mens-lace-up-shoes-u130-1\/"},"modified":"2023-10-19T14:40:30","modified_gmt":"2023-10-19T14:40:30","slug":"mens-lace-up-shoes-u130-1","status":"publish","type":"product","link":"https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/","title":{"rendered":"men&#8217;s lace-up shoes U130-1"},"content":{"rendered":"<p>Natural calf leather.<\/p>\n<p>The shoe is handcrafted and made to order, if not available in stock delivery times are 15 days.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Natural calf leather.<\/p>\n<p>The shoe is handcrafted and made to order, if not available in stock delivery times are 15 days.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":16095,"template":"","meta":[],"product_cat":[59,122],"product_tag":[],"class_list":["post-18300","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-lebohemien-men","product_cat-m-fall-winter","berocket_brand-le-bohemien-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LeBohemien men&#039;s lace-up shoes U130-1 | Verdecchia<\/title>\n<meta name=\"description\" content=\"Scarpa LeBohemien in pellame naturale vitello. La calzatura \u00e8 realizzata artigianalmente e su ordinazione, se non disponibile in magazzino i tempi di consegna sono di 15 giorni.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LeBohemien men&#039;s lace-up shoes U130-1 | Verdecchia\" \/>\n<meta property=\"og:description\" content=\"Scarpa LeBohemien in pellame naturale vitello. La calzatura \u00e8 realizzata artigianalmente e su ordinazione, se non disponibile in magazzino i tempi di consegna sono di 15 giorni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Verdecchia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/verdecchia.it\/wp-content\/uploads\/2023\/09\/U130-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1772\" \/>\n\t<meta property=\"og:image:height\" content=\"1535\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/\",\"url\":\"https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/\",\"name\":\"LeBohemien men's lace-up shoes U130-1 | Verdecchia\",\"isPartOf\":{\"@id\":\"https:\/\/verdecchia.it\/en\/#website\"},\"datePublished\":\"2023-10-19T14:40:30+00:00\",\"dateModified\":\"2023-10-19T14:40:30+00:00\",\"description\":\"Scarpa LeBohemien in pellame naturale vitello. La calzatura \u00e8 realizzata artigianalmente e su ordinazione, se non disponibile in magazzino i tempi di consegna sono di 15 giorni.\",\"breadcrumb\":{\"@id\":\"https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/verdecchia.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/verdecchia.it\/catalogo\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"men&#8217;s lace-up shoes U130-1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/verdecchia.it\/en\/#website\",\"url\":\"https:\/\/verdecchia.it\/en\/\",\"name\":\"Verdecchia Le Boh\u00e9mien\",\"description\":\"Since 1964 - Top Quality Shoes\",\"publisher\":{\"@id\":\"https:\/\/verdecchia.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/verdecchia.it\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/verdecchia.it\/en\/#organization\",\"name\":\"S.L.K. Verdecchia s.r.l.\",\"url\":\"https:\/\/verdecchia.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/verdecchia.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/verdecchia.it\/wp-content\/uploads\/2018\/07\/logo-sticky.jpg\",\"contentUrl\":\"https:\/\/verdecchia.it\/wp-content\/uploads\/2018\/07\/logo-sticky.jpg\",\"width\":77,\"height\":73,\"caption\":\"S.L.K. Verdecchia s.r.l.\"},\"image\":{\"@id\":\"https:\/\/verdecchia.it\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LeBohemien men's lace-up shoes U130-1 | Verdecchia","description":"Scarpa LeBohemien in pellame naturale vitello. La calzatura \u00e8 realizzata artigianalmente e su ordinazione, se non disponibile in magazzino i tempi di consegna sono di 15 giorni.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/","og_locale":"en_US","og_type":"article","og_title":"LeBohemien men's lace-up shoes U130-1 | Verdecchia","og_description":"Scarpa LeBohemien in pellame naturale vitello. La calzatura \u00e8 realizzata artigianalmente e su ordinazione, se non disponibile in magazzino i tempi di consegna sono di 15 giorni.","og_url":"https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/","og_site_name":"Verdecchia","og_image":[{"width":1772,"height":1535,"url":"https:\/\/verdecchia.it\/wp-content\/uploads\/2023\/09\/U130-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/","url":"https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/","name":"LeBohemien men's lace-up shoes U130-1 | Verdecchia","isPartOf":{"@id":"https:\/\/verdecchia.it\/en\/#website"},"datePublished":"2023-10-19T14:40:30+00:00","dateModified":"2023-10-19T14:40:30+00:00","description":"Scarpa LeBohemien in pellame naturale vitello. La calzatura \u00e8 realizzata artigianalmente e su ordinazione, se non disponibile in magazzino i tempi di consegna sono di 15 giorni.","breadcrumb":{"@id":"https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/verdecchia.it\/en\/catalog\/lebohemien-men\/m-fall-winter\/mens-lace-up-shoes-u130-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/verdecchia.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/verdecchia.it\/catalogo\/"},{"@type":"ListItem","position":3,"name":"men&#8217;s lace-up shoes U130-1"}]},{"@type":"WebSite","@id":"https:\/\/verdecchia.it\/en\/#website","url":"https:\/\/verdecchia.it\/en\/","name":"Verdecchia Le Boh\u00e9mien","description":"Since 1964 - Top Quality Shoes","publisher":{"@id":"https:\/\/verdecchia.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/verdecchia.it\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/verdecchia.it\/en\/#organization","name":"S.L.K. Verdecchia s.r.l.","url":"https:\/\/verdecchia.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/verdecchia.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/verdecchia.it\/wp-content\/uploads\/2018\/07\/logo-sticky.jpg","contentUrl":"https:\/\/verdecchia.it\/wp-content\/uploads\/2018\/07\/logo-sticky.jpg","width":77,"height":73,"caption":"S.L.K. Verdecchia s.r.l."},"image":{"@id":"https:\/\/verdecchia.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/verdecchia.it\/en\/wp-json\/wp\/v2\/product\/18300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verdecchia.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/verdecchia.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/verdecchia.it\/en\/wp-json\/wp\/v2\/media\/16095"}],"wp:attachment":[{"href":"https:\/\/verdecchia.it\/en\/wp-json\/wp\/v2\/media?parent=18300"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/verdecchia.it\/en\/wp-json\/wp\/v2\/product_cat?post=18300"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/verdecchia.it\/en\/wp-json\/wp\/v2\/product_tag?post=18300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}